{"id":11572,"date":"2024-08-12T13:17:33","date_gmt":"2024-08-12T11:17:33","guid":{"rendered":"https:\/\/www.kymco.es\/prensa\/?p=11572"},"modified":"2024-08-12T13:38:08","modified_gmt":"2024-08-12T11:38:08","slug":"kymco-espana-anuncia-sky-town-125-abs-2","status":"publish","type":"post","link":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/","title":{"rendered":"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg\"><img class=\"aligncenter size-full wp-image-11551\" src=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-200x133.jpg 200w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-300x200.jpg 300w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-370x247.jpg 370w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-400x267.jpg 400w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-600x400.jpg 600w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-768x512.jpg 768w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-800x533.jpg 800w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-900x600.jpg 900w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1-1024x683.jpg 1024w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<ul>\n<li><strong>KYMCO introduce un nuevo modelo urbano: es m\u00e1s seguro, ligero, con mejor respuesta y el primero en equipar de serie el ba\u00fal KY30, para guardar un segundo casco integral<\/strong><\/li>\n<li><strong>Dos colores (gris brillo y blanco brillo) a un precio de 2.999 euros con matr\u00edcula gratis<\/strong><\/li>\n<li><strong>Primera moto que neutraliza huella de carbono extra derivada del conflicto del Mar Rojo<\/strong><\/li>\n<\/ul>\n<p><strong>Madrid, 12 de agosto 2024. <\/strong>El nuevo scooter <strong>Sky Town 125 ABS<\/strong>, superior al superventas urbano KYMCO, ya tiene fecha oficial de lanzamiento en Espa\u00f1a, primer pa\u00eds del mundo donde estar\u00e1 disponible. Ser\u00e1 el <strong>2 de septiembre<\/strong>, y estar\u00e1 a disposici\u00f3n de los usuarios en todos los puntos oficiales KYMCO de Espa\u00f1a.<\/p>\n<p><em>\u201cOfrecer nuevas propuestas y apoyar la movilidad segura, \u00e1gil, urbana y eficiente con un modelo totalmente nuevo es siempre un deseo muy especial para toda nuestra red de distribuci\u00f3n, que estar\u00e1 totalmente preparada para arrancar el pr\u00f3ximo 2 de septiembre con el lanzamiento de este espectacular modelo<\/em>\u201d, ha afirmado <strong>Carlos Wang<\/strong>, director General de KYMCO Espa\u00f1a.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.kymco.es\/prensa\/attachment_category\/sky-town-125-abs\/\">&gt;&gt; Ver GALER\u00cdA Fotos Acci\u00f3n, Ambiente, Estudio y Anuncio &gt;&gt;<\/a><\/p>\n<p>El nuevo scooter KYMCO urbano, el <strong>primero en equipar de serie el ba\u00fal KY30<\/strong>, es m\u00e1s seguro, estable y con una respuesta como nunca antes. Disponible en dos colores (gris brillo o blanco brillo), el nuevo scooter supone un salto en la movilidad dos ruedas, con el<strong> nuevo motor<\/strong> -pensado en reducir al m\u00ednimo las emisiones-, y su rendimiento excepcional. Y todo ello, en un modelo totalmente nuevo en motor, en chasis, seguridad\u2026 y en su dise\u00f1o compacto que lo convierte en el scooter <strong>m\u00e1s ligero y m\u00e1s bajo<\/strong> hasta la fecha. Adem\u00e1s, es la primera moto del mercado en neutralizar su huella de carbono.<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.kymco.es\/prensa\/presskits\/c\/scooters-125\/\">&gt;&gt; Descarga Press Kit &gt;&gt;<\/a> <br \/>\n(compactados editables, video oficial, <br \/>\nficha t\u00e9cnica, fotos en alta\u2026)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4.jpg\"><img class=\"aligncenter size-full wp-image-11550\" src=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-200x133.jpg 200w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-300x200.jpg 300w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-370x247.jpg 370w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-400x267.jpg 400w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-600x400.jpg 600w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-768x512.jpg 768w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-800x533.jpg 800w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-900x600.jpg 900w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4-1024x683.jpg 1024w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-4.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Totalmente nuevo y superior<\/strong><\/p>\n<p>El nuevo Sky Town 125 ABS se coloca por encima del superventas KYMCO que ha liderado el ranking de veh\u00edculos de dos ruedas de todas las categor\u00edas del mercado durante varios ejercicios. El nuevo modelo Sky Town 125 ABS supera ampliamente al exitoso y scooter urbano Agility que acumula, en sus diferentes versiones de 125 cc, 90.000 unidades vendidas en los \u00faltimos 15 a\u00f1os:<\/p>\n<ul>\n<li><strong>M\u00e1s ligero, compacto y bajo.<\/strong> Pesa 126 kilos, su distancia entre ejes es de 132 cm y su distancia al suelo desde el asiento es solo de 77 cm.<\/li>\n<li>Destaca por tener una m<strong>ejor respuesta, con un motor (11 CV)<\/strong> pensado para reducir al m\u00ednimo las emisiones. Estas se encuentran muy lejos de los l\u00edmites permitidos de la normativa Euro 5 + que ser\u00e1 obligatoria para todas las motos nuevas en 2025. Es notable la suavidad de su arranque que est\u00e1 directamente vinculada con el nuevo chasis, que adem\u00e1s de ser un 20% m\u00e1s r\u00edgido, cuenta con un<strong> nuevo soporte de moto<\/strong>r. Ofrece gran estabilidad y control.<\/li>\n<li>Permite realizar 280 km con su dep\u00f3sito de 7 litros.<\/li>\n<li>Es m\u00e1s seguro, al equipar la centralita de A<strong>BS de doble canal (Bosch)<\/strong>; cuenta con disco de freno (delantero de 220 mm con pinza de doble pist\u00f3n de 25 mm; y disco trasero de 200 mm).<\/li>\n<li><strong>Ba\u00fal exclusivo de serie.<\/strong> El veh\u00edculo cuenta con un cofre bajo el asiento con capacidad de un <strong>casco integral,<\/strong> pero adem\u00e1s equipa de serie el ba\u00fal original KYMCO KY30, con capacidad para guardar otro <strong>casco integral o modular.<\/strong> Es un cofre del mismo color que la moto, elegante y ultra compacto.<\/li>\n<li>Otros elementos interesantes que aumentan la comodidad en los trayectos urbanos, como doble toma USB, doble guantera, pantalla LCD de alto contraste, etc.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1.jpg\"><img class=\"aligncenter size-full wp-image-11555\" src=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-200x133.jpg 200w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-300x200.jpg 300w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-370x247.jpg 370w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-400x267.jpg 400w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-600x400.jpg 600w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-768x512.jpg 768w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-800x533.jpg 800w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-900x600.jpg 900w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1-1024x683.jpg 1024w, https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/skytown-125-abs-ambiente-1.jpg 1200w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sostenibilidad<\/strong><\/p>\n<p>El veh\u00edculo ser\u00e1 la <strong>primera moto que neutraliza huella de carbono.<\/strong> Human Mobility, que controla KYMCO en Espa\u00f1a, es la \u00fanica compa\u00f1\u00eda del sector dos ruedas que de forma voluntaria cuenta con ISO 14064-1 de huella de carbono, dentro de su compromiso con la sostenibilidad. \u00a0La compa\u00f1\u00eda ha aprobado neutralizar <strong>la mitad de las emisiones extras<\/strong> derivadas del mayor recorrido (incremento del 56%) que realizan las navieras ante el conflicto del Mar Rojo que persiste desde enero.<\/p>\n<p>La nueva ruta naviera por Cabo de Nueva Esperanza ha originado a la compa\u00f1\u00eda un exigente reto de sostenibilidad que se suma a los desaf\u00edos conocidos (mayores costes y tiempos). Tras cinco a\u00f1os consecutivos de investigaci\u00f3n, inversi\u00f3n y ajustes internos en materia medioambiental, Human Mobility se ha comprometido a neutralizar en 14,1 kilos de C02 por moto, que supone el 50% del incremento de las emisiones.<\/p>\n<p>Los usuarios pueden acceder al nuevo scooter a un precio de 2.999 euros (PVR) con<strong> matr\u00edcula gratis.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: center;\"><a class=\"fb-icon-element-1 fb-icon-element fontawesome-icon fa-file-alt far circle-yes fusion-text-flow fusion-link\" style=\"font-size:28.16px;line-height:54.32px;height:56.32px;width:56.32px;border-width:1px;margin-right:16px;\" href=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2020\/06\/sondeo-kymco-impactocovid19.pdf\" aria-label=\"Link to https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2020\/06\/sondeo-kymco-impactocovid19.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><\/a><style>a.fb-icon-element.fontawesome-icon.fb-icon-element-1{ color: #ffffff; background-color: #333338; border-color: #333338;}a.fb-icon-element.fontawesome-icon.fb-icon-element-1:hover { color: #ffffff; background-color: #333338; border-color: #333338;}<\/style>\u00a0<a href=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/06\/2024-ft-skytown-125-abs.pdf\"><strong><span style=\"font-size: 20px;\"> Ficha T\u00e9cnica Sky Town 125 ABS<\/span><\/strong><\/a><\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cOfrecer nuevas propuestas y apoyar la movilidad segura, \u00e1gil, urbana y eficiente con un modelo totalmente nuevo es siempre un deseo muy especial para toda nuestra red de distribuci\u00f3n, que estar\u00e1 totalmente preparada para arrancar el pr\u00f3ximo 2 de septiembre con el lanzamiento de este espectacular modelo\u201d, ha afirmado Carlos Wang, director General de KYMCO Espa\u00f1a.<\/p>\n","protected":false},"author":2,"featured_media":11551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[520,449],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"\u201cOfrecer nuevas propuestas y apoyar la movilidad segura, \u00e1gil, urbana y eficiente con un modelo totalmente nuevo es siempre un deseo muy especial para toda nuestra red de distribuci\u00f3n, que estar\u00e1 totalmente preparada para arrancar el pr\u00f3ximo 2 de septiembre con el lanzamiento de este espectacular modelo\u201d, ha afirmado Carlos Wang, director General de KYMCO Espa\u00f1a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/\" \/>\n<meta property=\"og:site_name\" content=\"KYMCO Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-12T11:17:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T11:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"KYMCO Espa\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kymco.es\/prensa\/#website\",\"url\":\"https:\/\/www.kymco.es\/prensa\/\",\"name\":\"KYMCO Espa\\u00f1a\",\"description\":\"Marca de movilidad personal\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kymco.es\/prensa\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg\",\"contentUrl\":\"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#webpage\",\"url\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/\",\"name\":\"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/www.kymco.es\/prensa\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#primaryimage\"},\"datePublished\":\"2024-08-12T11:17:33+00:00\",\"dateModified\":\"2024-08-12T11:38:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.kymco.es\/prensa\/#\/schema\/person\/b315bb551f7fe40b3f8f1b4768f556c4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.kymco.es\/prensa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.kymco.es\/prensa\/#\/schema\/person\/b315bb551f7fe40b3f8f1b4768f556c4\",\"name\":\"KYMCO Espa\\u00f1a\",\"url\":\"https:\/\/www.kymco.es\/prensa\/author\/vanessasaedrin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/","og_locale":"es_ES","og_type":"article","og_title":"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\u00f1a","og_description":"\u201cOfrecer nuevas propuestas y apoyar la movilidad segura, \u00e1gil, urbana y eficiente con un modelo totalmente nuevo es siempre un deseo muy especial para toda nuestra red de distribuci\u00f3n, que estar\u00e1 totalmente preparada para arrancar el pr\u00f3ximo 2 de septiembre con el lanzamiento de este espectacular modelo\u201d, ha afirmado Carlos Wang, director General de KYMCO Espa\u00f1a.","og_url":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/","og_site_name":"KYMCO Espa\u00f1a","article_published_time":"2024-08-12T11:17:33+00:00","article_modified_time":"2024-08-12T11:38:08+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg","path":"\/var\/www\/html\/kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg","size":"full","id":11551,"alt":"","pixels":960000,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"KYMCO Espa\u00f1a","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.kymco.es\/prensa\/#website","url":"https:\/\/www.kymco.es\/prensa\/","name":"KYMCO Espa\u00f1a","description":"Marca de movilidad personal","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kymco.es\/prensa\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#primaryimage","inLanguage":"es","url":"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg","contentUrl":"https:\/\/www.kymco.es\/prensa\/wp-content\/uploads\/2024\/08\/sky-town-125-abs-accion-1.jpg","width":1200,"height":800},{"@type":"WebPage","@id":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#webpage","url":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/","name":"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre - KYMCO Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.kymco.es\/prensa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#primaryimage"},"datePublished":"2024-08-12T11:17:33+00:00","dateModified":"2024-08-12T11:38:08+00:00","author":{"@id":"https:\/\/www.kymco.es\/prensa\/#\/schema\/person\/b315bb551f7fe40b3f8f1b4768f556c4"},"breadcrumb":{"@id":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kymco.es\/prensa\/nota-de-prensa\/kymco-espana-anuncia-sky-town-125-abs-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.kymco.es\/prensa\/"},{"@type":"ListItem","position":2,"name":"Sky Town 125 ABS, superior al superventas KYMCO, llega el 2 de septiembre"}]},{"@type":"Person","@id":"https:\/\/www.kymco.es\/prensa\/#\/schema\/person\/b315bb551f7fe40b3f8f1b4768f556c4","name":"KYMCO Espa\u00f1a","url":"https:\/\/www.kymco.es\/prensa\/author\/vanessasaedrin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/posts\/11572"}],"collection":[{"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/comments?post=11572"}],"version-history":[{"count":3,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/posts\/11572\/revisions"}],"predecessor-version":[{"id":11577,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/posts\/11572\/revisions\/11577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/media\/11551"}],"wp:attachment":[{"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/media?parent=11572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/categories?post=11572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kymco.es\/prensa\/wp-json\/wp\/v2\/tags?post=11572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}